{"id":29,"date":"2022-07-26T11:48:06","date_gmt":"2022-07-26T09:48:06","guid":{"rendered":"https:\/\/bwi.earth\/?page_id=29"},"modified":"2026-07-09T12:32:53","modified_gmt":"2026-07-09T10:32:53","slug":"a-propos","status":"publish","type":"page","link":"https:\/\/bwi.earth\/fr\/a-propos\/","title":{"rendered":"A propos"},"content":{"rendered":"<section class=\"hero-full \">\n    <div class=\"swiper\">\n        <div class=\"swiper-wrapper\">\n                            <div class=\"swiper-slide\" style=\"background-color: #86efaa\">\n                    <div class=\"container-img\">\n                        <img decoding=\"async\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/etang.png\" alt=\"\">\n                    <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n\n    <div class=\"wrap\">\n                    <h1 class=\"block-title title-h1\"><p>BWI <b>digitalise les bassins versants<\/b><br><\/p><\/h1>\n        \n                    <div class=\"hero-full__content\">\n                BWI, acronyme de Blue Water Intelligence, est une soci\u00e9t\u00e9 sp\u00e9cialis\u00e9e dans l&rsquo;hydrologie, cr\u00e9\u00e9e en juin 2022 \u00e0 Toulouse, en France. BWI est sp\u00e9cialis\u00e9e dans la simulation en quasi temps-r\u00e9el et dans la fourniture de pr\u00e9visions des d\u00e9bits, des niveaux et des volumes d&rsquo;eau de surface continentale partout dans le monde. Le slogan de BWI en cinq mots est \u00ab\u00a0BWI num\u00e9rise les bassins versants\u00a0\u00bb. Les BWI \u00e9tendent continuellement leurs services \u00e0 de nouvelles zones g\u00e9ographiques, tout en am\u00e9liorant leurs performances dans les zones d\u00e9j\u00e0 couvertes par les BWI.            <\/div>\n        \n            <\/div>\n<\/section>\n\n\n    <section class=\"gut-content-repeater bg-color-gris\">\n        <div class=\"wrap small\">\n                            <h2 class=\"block-title title-h2\"><p>BWI fournit des <b>pr\u00e9visions sur les d\u00e9bits et sur la hauteur des rivi\u00e8res<\/b><br><\/p><\/h2>\n            \n            <div class=\"rows\">\n                                    <div class=\"row\">\n                        <div class=\"content\">\n                                                            <h3 class=\"row-title\">Donn\u00e9es et informations sur l&rsquo;eau douce <\/h3>\n                            \n                                                            <div class=\"text-container\">\n                                                                            <span class=\"number\">3%<\/span>\n                                    \n                                                                            <div class=\"text\">\n                                            <div><span lang=\"EN-US\">de l&rsquo;eau de la plan\u00e8te <strong>est douce<\/strong>. Ensemble, prenons soin de cette ressource rare mais vitale afin d&rsquo;en assurer la disponibilit\u00e9 pour les g\u00e9n\u00e9rations futures !<\/span><\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                    <\/div>\n\n                        <div class=\"image-container\">\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"526\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/ile-montagne.png\" class=\"attachment-banner size-banner\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/ile-montagne.png 605w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/ile-montagne-300x261.png 300w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>                                                    <\/div>\n                    <\/div>\n                                    <div class=\"row\">\n                        <div class=\"content\">\n                                                            <h3 class=\"row-title\">Une d\u00e9marche sophistiqu\u00e9e pour pr\u00e9voir les d\u00e9bits des eaux continentales, les niveaux d&rsquo;eau et la qualit\u00e9 de l&rsquo;eau<\/h3>\n                            \n                                                            <div class=\"text-container\">\n                                    \n                                                                            <div class=\"text\">\n                                            <p style=\"font-weight: 400;\">BWI conjugue des donn\u00e9es <em>in situ<\/em>, des observations spatiales et de l&rsquo;apprentissage automatique pour alimenter et renforcer les mod\u00e8les hydrologiques et hydrodynamiques.<\/p>\n<p style=\"font-weight: 400;\">En tant que fournisseur de services en ligne par licence, BWI vise \u00e0 fournir des donn\u00e9es hydrologiques \u00e9volutives &#8211; dans l&rsquo;espace et dans le temps &#8211; pour faire face au <strong>stress hydrique induit par le changement climatique.<\/strong><\/p>\n                                        <\/div>\n                                                                    <\/div>\n                                                    <\/div>\n\n                        <div class=\"image-container\">\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"326\" height=\"510\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/banquise.png\" class=\"attachment-banner size-banner\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/banquise.png 326w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/banquise-192x300.png 192w\" sizes=\"auto, (max-width: 326px) 100vw, 326px\" \/>                                                    <\/div>\n                    <\/div>\n                                    <div class=\"row\">\n                        <div class=\"content\">\n                                                            <h3 class=\"row-title\">Aidez les gouvernements et les entreprises \u00e0 s&rsquo;adapter au changement climatique<\/h3>\n                            \n                                                            <div class=\"text-container\">\n                                    \n                                                                            <div class=\"text\">\n                                            <div>\n<p>L&rsquo;am\u00e9lioration de la pr\u00e9vision de la disponibilit\u00e9 des ressources en eau, de la qualit\u00e9 de l&rsquo;eau, des pr\u00e9visions d&rsquo;inondation, de la gestion de l&rsquo;eau et des pr\u00e9visions de s\u00e9cheresse \u00e0 l&rsquo;\u00e9chelle locale et r\u00e9gionale <strong>aidera les autorit\u00e9s publiques et les entreprises \u00e0 renforcer leur r\u00e9silience climatique<\/strong> et permettra aux scientifiques de mieux comprendre le cycle de l&rsquo;eau.<\/p>\n<p>BWI souhaite \u00e9galement <strong>acc\u00e9l\u00e9rer la transition vers une soci\u00e9t\u00e9 faiblement \u00e9mettrice en carbone<\/strong> en soutenant les industries peu \u00e9missives, comme la production d&rsquo;hydro\u00e9lectricit\u00e9 ou comme le transport fluvial.<\/p>\n<\/div>\n                                        <\/div>\n                                                                    <\/div>\n                                                    <\/div>\n\n                        <div class=\"image-container\">\n                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1162\" height=\"883\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/ile-nuage.png\" class=\"attachment-banner size-banner\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/ile-nuage.png 1162w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/ile-nuage-300x228.png 300w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/ile-nuage-1024x778.png 1024w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/ile-nuage-768x584.png 768w\" sizes=\"auto, (max-width: 1162px) 100vw, 1162px\" \/>                                                    <\/div>\n                    <\/div>\n                            <\/div>\n        <\/div>\n    <\/section>\n\n\n\n    <section class=\"gut-small-slider bg-color-blanc\">\n        <div class=\"wrap\">\n                            <h2 class=\"block-title title-h2\"><b>Stations virtuelles hydrologiques<\/b> pour aider nos clients \u00e0 num\u00e9riser les bassins versants<\/h2>\n            \n            <div class=\"slider__navigation\">\n                <button class=\"slider__navigation--prev\"><span class=\"icon-chevron-right\"><\/span><\/button>\n                <button class=\"slider__navigation--next\"><span class=\"icon-chevron-right\"><\/span><\/button>\n            <\/div>\n            <div class=\"swiper\">\n                <div class=\"swiper-wrapper\">\n                                            <div class=\"slide swiper-slide\">\n                                                            <span class=\"slide__categorie\">Pouvoirs publics et institutions<\/span>\n                            \n                                                            <h3 class=\"slide-title\">Pr\u00e9voyez les risques hydroclimatiques et acc\u00e9dez \u00e0 des donn\u00e9es sur les eaux continentales en quasi temps-r\u00e9el (qualit\u00e9, d\u00e9bits, niveaux, volumes).<\/h3>\n                            \n                                                            <div class=\"slide__content\">\n                                    BWI a d\u00e9velopp\u00e9 un syst\u00e8me d&rsquo;alerte pr\u00e9coce aux inondations et \u00e0 la s\u00e9cheresse pour les gestionnaires de risques, les municipalit\u00e9s, les autorit\u00e9s en charge de la gestion des bassins et les institutions financi\u00e8res internationales. Des pr\u00e9visions d&rsquo;inondation pr\u00e9cises simplifient la pr\u00e9paration et la r\u00e9ponse aux catastrophes. \r\n\r\nBWI fournit \u00e9galement des solutions de surveillance pr\u00e9dictive de la qualit\u00e9 de l&rsquo;eau.                                <\/div>\n                                                    <\/div>\n                                            <div class=\"slide swiper-slide\">\n                                                            <span class=\"slide__categorie\">Gestionnaires de portefeuilles scientifiques et de risques<\/span>\n                            \n                                                            <h3 class=\"slide-title\">Donn\u00e9es sur les niveaux d&rsquo;eau, mises \u00e0 jour quotidiennement, provenant d&rsquo;une constellation hydrologique en orbite basse de nanosatellites.<\/h3>\n                            \n                                                            <div class=\"slide__content\">\n                                    BWI travaille \u00e0 faire du concept SMASH (Small Altimetry Satellites for Hydrology), n\u00e9 au centre de recherche LEGOS et con\u00e7u au CNES (phase A achev\u00e9e), une r\u00e9alit\u00e9 afin de couvrir le globe terrestre avec des points de mesure de l\u2019\u00e9l\u00e9vation des eaux de surface continentales mis \u00e0 jour quotidiennement.\r\n\r\n30.000 points de donn\u00e9es comparables sur l\u2019\u00e9l\u00e9vation des eaux continentales, mis \u00e0 jour quotidiennement, constitueraient une mati\u00e8re premi\u00e8re formidable pour les scientifiques, pour les ONG, pour les gouvernements et pour les autorit\u00e9s de bassin, ainsi que pour les entreprises mondiales telles que les compagnies d\u2019assurances et encore d\u2019autres industries.                                <\/div>\n                                                    <\/div>\n                                            <div class=\"slide swiper-slide\">\n                                                            <span class=\"slide__categorie\">Exploitants de centrales hydro\u00e9lectriques au fil de l&rsquo;eau et agr\u00e9gateurs d&rsquo;\u00e9nergie<\/span>\n                            \n                                                            <h3 class=\"slide-title\">Pr\u00e9voir avec pr\u00e9cision le d\u00e9bit des rivi\u00e8res et les niveaux d&rsquo;eau<\/h3>\n                            \n                                                            <div class=\"slide__content\">\n                                    BWI permet aux op\u00e9rateurs de centrales hydro\u00e9lectriques au fil de l&rsquo;eau d&rsquo;augmenter leurs revenus en faisant de l&rsquo;int\u00e9gration des pr\u00e9visions de d\u00e9bit des rivi\u00e8res dans les processus op\u00e9rationnels une r\u00e9alit\u00e9.\r\n\r\nBWI est capable de pr\u00e9voir avec pr\u00e9cision le d\u00e9bit des rivi\u00e8res et de fournir ces pr\u00e9cieuses donn\u00e9es hydrologiques aux op\u00e9rateurs hydro\u00e9lectriques et aux n\u00e9gociants en \u00e9nergie par le biais d&rsquo;une API.\r\n                                <\/div>\n                                                    <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n\n\n\n    <section class=\"gut-collaborators bg-color-blanc\">\n        <div class=\"wrap\">\n                            <h2 class=\"block-title title-h2\">Les talents qui composent la \u00ab Blue team \u00bb<\/h2>\n            \n            <div class=\"slider__navigation\">\n                <button class=\"slider__navigation--prev\"><span class=\"icon-chevron-right\"><\/span><\/button>\n                <button class=\"slider__navigation--next\"><span class=\"icon-chevron-right\"><\/span><\/button>\n            <\/div>\n\n            <div class=\"swiper\">\n                <div class=\"swiper-wrapper\">\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"154\" height=\"162\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/philippe.png\" class=\"attachment-medium size-medium\" alt=\"\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Philippe Gautier, Ing.<\/p>\n\n\n                                                            <p class=\"function\">Pr\u00e9sident<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/philippe-gautier-839169a2\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Philippe Gautier, Ing.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/05\/BWI_Photo-4-1-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/05\/BWI_Photo-4-1-200x300.jpg 200w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/05\/BWI_Photo-4-1-683x1024.jpg 683w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/05\/BWI_Photo-4-1-scaled.jpg 1707w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Jeremy Fain, M.Sc.<\/p>\n\n\n                                                            <p class=\"function\">Directeur G\u00e9n\u00e9ral<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/jeremyfain\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Jeremy Fain, M.Sc.\"><\/a>\n                                                                                                                <a target=\"_blank\" href=\"https:\/\/bwi.earth\/introducing-jeremy-fain\/\" class=\"icon-team icon-url\" title=\"Url of  Jeremy Fain, M.Sc.\"><span><\/span><\/a>\n                                                                    <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2025\/12\/Lise-300x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2025\/12\/Lise-300x300.jpeg 300w, https:\/\/bwi.earth\/wp-content\/uploads\/2025\/12\/Lise-150x150.jpeg 150w, https:\/\/bwi.earth\/wp-content\/uploads\/2025\/12\/Lise.jpeg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Lise Ferri\u00e8res, M.Sc.<\/p>\n\n\n                                                            <p class=\"function\">Directrice G\u00e9n\u00e9rale adjointe<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/lise-ferrieres-654a403\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Lise Ferri\u00e8res, M.Sc.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"154\" height=\"162\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/piotr.png\" class=\"attachment-medium size-medium\" alt=\"\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"Poland\" class=\"fi fi-pl\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Piotr St\u0119pnicki, M.Sc.<\/p>\n\n\n                                                            <p class=\"function\">Directeur technique &#8211; Sp\u00e9cialiste de la vision par ordinateur<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/piotr-stepnicki\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Piotr St\u0119pnicki, M.Sc.\"><\/a>\n                                                                                                                <a target=\"_blank\" href=\"https:\/\/bwi.earth\/introducing-piotr-stepnicki\/\" class=\"icon-team icon-url\" title=\"Url of  Piotr St\u0119pnicki, M.Sc.\"><span><\/span><\/a>\n                                                                    <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/05\/Photo_BWI_03_04_2024-17-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/05\/Photo_BWI_03_04_2024-17-200x300.jpg 200w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/05\/Photo_BWI_03_04_2024-17-683x1024.jpg 683w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/05\/Photo_BWI_03_04_2024-17-768x1152.jpg 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/05\/Photo_BWI_03_04_2024-17-1024x1536.jpg 1024w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/05\/Photo_BWI_03_04_2024-17-1365x2048.jpg 1365w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/05\/Photo_BWI_03_04_2024-17-8x12.jpg 8w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/05\/Photo_BWI_03_04_2024-17-720x1080.jpg 720w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/05\/Photo_BWI_03_04_2024-17-scaled.jpg 1706w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Annie Puchot, Ing.<\/p>\n\n\n                                                            <p class=\"function\">Ing\u00e9nieure en syst\u00e8mes spatiaux &#8211; Chef de mission Hydrologie Haute Revisite<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/annie-puchot-b3949182\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Annie Puchot, Ing.\"><\/a>\n                                                                                                                <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/annie-puchot-b3949182\" class=\"icon-team icon-url\" title=\"Url of  Annie Puchot, Ing.\"><span><\/span><\/a>\n                                                                    <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"233\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2025\/07\/Photo-FA-233x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2025\/07\/Photo-FA-233x300.jpg 233w, https:\/\/bwi.earth\/wp-content\/uploads\/2025\/07\/Photo-FA.jpg 688w\" sizes=\"auto, (max-width: 233px) 100vw, 233px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Frank Airoldi, Ing.<\/p>\n\n\n                                                            <p class=\"function\">Directeur de Programme &#8211; Sp\u00e9cialiste d&rsquo;ing\u00e9nierie spatiale<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/frank-airoldi-a4864419\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Frank Airoldi, Ing.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"154\" height=\"162\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/aurelien.png\" class=\"attachment-medium size-medium\" alt=\"\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Aur\u00e9lien Bricier, Ing.<\/p>\n\n\n                                                            <p class=\"function\">Ing\u00e9nieur R&#038;D<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/abricier\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Aur\u00e9lien Bricier, Ing.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/10\/pascal-cauquil-bwi-212x300.png\" class=\"attachment-medium size-medium\" alt=\"pascal cauquil bwi\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/10\/pascal-cauquil-bwi-212x300.png 212w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/10\/pascal-cauquil-bwi-724x1024.png 724w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/10\/pascal-cauquil-bwi-768x1086.png 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/10\/pascal-cauquil-bwi-1086x1536.png 1086w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/10\/pascal-cauquil-bwi-764x1080.png 764w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/10\/pascal-cauquil-bwi.png 1414w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Pascal Cauquil, Ing.<\/p>\n\n\n                                                            <p class=\"function\">Ing\u00e9nieur segment sol <\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/pascal-cauquil-5155612a4\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Pascal Cauquil, Ing.\"><\/a>\n                                                                                                                <a target=\"_blank\" href=\"https:\/\/bwi.earth\/interview-pascal-cauquil\/\" class=\"icon-team icon-url\" title=\"Url of  Pascal Cauquil, Ing.\"><span><\/span><\/a>\n                                                                    <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/06\/matteo.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/06\/matteo.jpeg 300w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/06\/matteo-150x150.jpeg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"Italy\" class=\"fi fi-it\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Matteo Ciocca, Ph.D.<\/p>\n\n\n                                                            <p class=\"function\">Chef de produit<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/matteociocca\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Matteo Ciocca, Ph.D.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"229\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/06\/benoit.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Beno\u00eet Nigon, Ph.D.<\/p>\n\n\n                                                            <p class=\"function\">Hydrog\u00e9ologue<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/benoit-nigon-448b4177\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Beno\u00eet Nigon, Ph.D.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"154\" height=\"162\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/anil.png\" class=\"attachment-medium size-medium\" alt=\"\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"Nepal\" class=\"fi fi-np\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Anil Kumar Khanal, Ph.D.<\/p>\n\n\n                                                            <p class=\"function\">Responsable de zone<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/anil-khanal-6a518b3b\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Anil Kumar Khanal, Ph.D.\"><\/a>\n                                                                                                                <a target=\"_blank\" href=\"https:\/\/bwi.earth\/introducing-anil-khanal\/\" class=\"icon-team icon-url\" title=\"Url of  Anil Kumar Khanal, Ph.D.\"><span><\/span><\/a>\n                                                                    <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/HD_Portrait-31-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/HD_Portrait-31-200x300.jpg 200w, https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/HD_Portrait-31-683x1024.jpg 683w, https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/HD_Portrait-31-768x1152.jpg 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/HD_Portrait-31-1024x1536.jpg 1024w, https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/HD_Portrait-31-1365x2048.jpg 1365w, https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/HD_Portrait-31-720x1080.jpg 720w, https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/HD_Portrait-31-scaled.jpg 1707w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Jacques Bensemhoun, B.A.<\/p>\n\n\n                                                            <p class=\"function\">Responsable des ventes &#8211; Sp\u00e9cialiste des logiciels d&rsquo;entreprise<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/jacquesbensemhoun\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Jacques Bensemhoun, B.A.\"><\/a>\n                                                                                                                <a target=\"_blank\" href=\"https:\/\/bwi.earth\/introducing-jacques-bensemhoun\/\" class=\"icon-team icon-url\" title=\"Url of  Jacques Bensemhoun, B.A.\"><span><\/span><\/a>\n                                                                    <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"154\" height=\"162\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/audrey.png\" class=\"attachment-medium size-medium\" alt=\"\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Audrey Gabbay, Ing.<\/p>\n\n\n                                                            <p class=\"function\">Ing\u00e9nieure logiciel &#8211; Sp\u00e9cialiste en vision par ordinateur<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/audrey-gabbay-02198\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Audrey Gabbay, Ing.\"><\/a>\n                                                                                                                <a target=\"_blank\" href=\"https:\/\/bwi.earth\/introducing-audrey-gabbay\/\" class=\"icon-team icon-url\" title=\"Url of  Audrey Gabbay, Ing.\"><span><\/span><\/a>\n                                                                    <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/12\/Photo_BWI_Montpellier-2-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/12\/Photo_BWI_Montpellier-2-200x300.jpg 200w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/12\/Photo_BWI_Montpellier-2-683x1024.jpg 683w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/12\/Photo_BWI_Montpellier-2-768x1152.jpg 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/12\/Photo_BWI_Montpellier-2-1024x1536.jpg 1024w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/12\/Photo_BWI_Montpellier-2-1365x2048.jpg 1365w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/12\/Photo_BWI_Montpellier-2-8x12.jpg 8w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/12\/Photo_BWI_Montpellier-2-720x1080.jpg 720w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/12\/Photo_BWI_Montpellier-2-scaled.jpg 1707w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"Lebanon\" class=\"fi fi-lb\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Mohamad Hamze, Ph.D.<\/p>\n\n\n                                                            <p class=\"function\">Responsable de zone &#8211; Sp\u00e9cialiste de t\u00e9l\u00e9d\u00e9tection pour l&rsquo;agriculture et l&rsquo;irrigation<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/mohamad-hamze-a35abb123\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Mohamad Hamze, Ph.D.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"286\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/07\/Ilhom-286x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/07\/Ilhom-286x300.jpg 286w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/07\/Ilhom-976x1024.jpg 976w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/07\/Ilhom-768x806.jpg 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/07\/Ilhom-1029x1080.jpg 1029w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/07\/Ilhom.jpg 1425w\" sizes=\"auto, (max-width: 286px) 100vw, 286px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                    <span title=\"Tajikistan\" class=\"fi fi-tj\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Ilhom Ismoilov, M.Sc.<\/p>\n\n\n                                                            <p class=\"function\">Area Manager<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-15-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-15-200x300.jpg 200w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-15-683x1024.jpg 683w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-15-768x1152.jpg 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-15-1024x1536.jpg 1024w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-15-720x1080.jpg 720w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-15.jpg 1365w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Thibault Lebeke, Ing.<\/p>\n\n\n                                                            <p class=\"function\">Responsable des affaires industrielles<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/thibault-l-13a706a4\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Thibault Lebeke, Ing.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/HD_Portrait-7-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/HD_Portrait-7-200x300.jpg 200w, https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/HD_Portrait-7.jpg 533w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Iliana Vincenti, Ing.<\/p>\n\n\n                                                            <p class=\"function\">Ing\u00e9nieure R&#038;D &#8211; Sp\u00e9cialiste en vision par ordinateur<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/iliana-vincenti-966689131\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Iliana Vincenti, Ing.\"><\/a>\n                                                                                                                <a target=\"_blank\" href=\"https:\/\/bwi.earth\/introducing-iliana-vincenti\/\" class=\"icon-team icon-url\" title=\"Url of  Iliana Vincenti, Ing.\"><span><\/span><\/a>\n                                                                    <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Sept_2025-114-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Sept_2025-114-200x300.jpg 200w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Sept_2025-114-683x1024.jpg 683w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Sept_2025-114-768x1152.jpg 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Sept_2025-114-1024x1536.jpg 1024w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Sept_2025-114-720x1080.jpg 720w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Sept_2025-114.jpg 1365w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"Ukraine\" class=\"fi fi-ua\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Illia Bovtriuk, Ing.<\/p>\n\n\n                                                            <p class=\"function\">Ing\u00e9nieur logiciel \u2013 Sp\u00e9cialiste en Math\u00e9matiques et Informatique<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/illia-bovtriuk\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Illia Bovtriuk, Ing.\"><\/a>\n                                                                                                                <a target=\"_blank\" href=\"https:\/\/bwi.earth\/introducing-illia-bovtriuk-software-engineer\/\" class=\"icon-team icon-url\" title=\"Url of  Illia Bovtriuk, Ing.\"><span><\/span><\/a>\n                                                                    <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/06\/thomas.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/06\/thomas.jpeg 300w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/06\/thomas-150x150.jpeg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Thomas Aghavnian, Ph.D.<\/p>\n\n\n                                                            <p class=\"function\">Ing\u00e9nieur R&#038;D<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/thomas-aghavnian\/?locale=en_US\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Thomas Aghavnian, Ph.D.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-23-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-23-200x300.jpg 200w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-23-683x1024.jpg 683w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-23-768x1152.jpg 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-23-1024x1536.jpg 1024w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-23-720x1080.jpg 720w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-23.jpg 1365w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Roxane Blattes, Ph.D.<\/p>\n\n\n                                                            <p class=\"function\">Responsable du pilotage des projets<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/roxaneblattes\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Roxane Blattes, Ph.D.\"><\/a>\n                                                                                                                <a target=\"_blank\" href=\"https:\/\/bwi.earth\/introducing-roxane-blattes\/\" class=\"icon-team icon-url\" title=\"Url of  Roxane Blattes, Ph.D.\"><span><\/span><\/a>\n                                                                    <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-19-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-19-200x300.jpg 200w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-19-683x1024.jpg 683w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-19-768x1152.jpg 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-19-1024x1536.jpg 1024w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-19-720x1080.jpg 720w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-19.jpg 1365w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Fran\u00e7ois Verdeil, Ph.D.<\/p>\n\n\n                                                            <p class=\"function\">Ing\u00e9nieur en traitement du signal<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/francois-verdeil-998265134\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Fran\u00e7ois Verdeil, Ph.D.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-29-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-29-200x300.jpg 200w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-29-683x1024.jpg 683w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-29-768x1152.jpg 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-29-1024x1536.jpg 1024w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-29-720x1080.jpg 720w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-29.jpg 1365w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                    <span title=\"Lebanon\" class=\"fi fi-lb\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Bassam El Hajj Chehade, Ph.D.<\/p>\n\n\n                                                            <p class=\"function\">Ing\u00e9nieur en traitement du signal<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/bassam-chehade-phd-328a69105\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Bassam El Hajj Chehade, Ph.D.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-32-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-32-200x300.jpg 200w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-32-683x1024.jpg 683w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-32-768x1152.jpg 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-32-1024x1536.jpg 1024w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-32-720x1080.jpg 720w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Photos_2026-32.jpg 1365w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"China\" class=\"fi fi-cn\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Hanbing Peng, Ph.D.<\/p>\n\n\n                                                            <p class=\"function\">Ing\u00e9nieur en d\u00e9termination pr\u00e9cise d&rsquo;orbite<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/hanbing-peng-46a322243\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Hanbing Peng, Ph.D.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"258\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/08\/201910-\u00a9JPC-Sasha-1-258x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/08\/201910-\u00a9JPC-Sasha-1-258x300.jpg 258w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/08\/201910-\u00a9JPC-Sasha-1-882x1024.jpg 882w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/08\/201910-\u00a9JPC-Sasha-1-768x892.jpg 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/08\/201910-\u00a9JPC-Sasha-1-1323x1536.jpg 1323w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/08\/201910-\u00a9JPC-Sasha-1-1764x2048.jpg 1764w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/08\/201910-\u00a9JPC-Sasha-1-930x1080.jpg 930w\" sizes=\"auto, (max-width: 258px) 100vw, 258px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"Turkey\" class=\"fi fi-tr\"><\/span>\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Sasha Keskin, M.Sc.<\/p>\n\n\n                                                            <p class=\"function\">Responsable technique DevOps &#8211; Ing\u00e9nieur plateforme<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/sasha-keskin-1a0a37170\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Sasha Keskin, M.Sc.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/kCtagxRw-200x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/kCtagxRw-200x300.jpeg 200w, https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/kCtagxRw-683x1024.jpeg 683w, https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/kCtagxRw-768x1152.jpeg 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/kCtagxRw-1024x1536.jpeg 1024w, https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/kCtagxRw-720x1080.jpeg 720w, https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/kCtagxRw.jpeg 1365w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"Lebanon\" class=\"fi fi-lb\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Georges Aazan, Ph.D.<\/p>\n\n\n                                                            <p class=\"function\">Ing\u00e9nieur R&#038;D &#8211; Sp\u00e9cialiste en Math\u00e9matiques Appliqu\u00e9es<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/georges-aazan-5b9419295\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Georges Aazan, Ph.D.\"><\/a>\n                                                                                                                <a target=\"_blank\" href=\"https:\/\/bwi.earth\/introducing-georges-aazan\/\" class=\"icon-team icon-url\" title=\"Url of  Georges Aazan, Ph.D.\"><span><\/span><\/a>\n                                                                    <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Sept_2025-121-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Sept_2025-121-200x300.jpg 200w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Sept_2025-121-683x1024.jpg 683w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Sept_2025-121-768x1152.jpg 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Sept_2025-121-1024x1536.jpg 1024w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Sept_2025-121-720x1080.jpg 720w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Sept_2025-121.jpg 1365w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\"> Lo\u00efc Grosset\u00eate, Ph.D<\/p>\n\n\n                                                            <p class=\"function\">Ing\u00e9nieur R&#038;D &#8211; Sp\u00e9cialiste en Apprentissage Automatique<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/loic-grossetete\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of   Lo\u00efc Grosset\u00eate, Ph.D\"><\/a>\n                                                                                                                <a target=\"_blank\" href=\"https:\/\/bwi.earth\/introducing-loic-grossetete-ai-software-engineer\/\" class=\"icon-team icon-url\" title=\"Url of   Lo\u00efc Grosset\u00eate, Ph.D\"><span><\/span><\/a>\n                                                                    <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"154\" height=\"162\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/mathieu.png\" class=\"attachment-medium size-medium\" alt=\"\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Mathieu Arthaud, Ing.<\/p>\n\n\n                                                            <p class=\"function\">Ing\u00e9nieur logiciel &#8211; Sp\u00e9cialiste SIG<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/mathieu-arthaud\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Mathieu Arthaud, Ing.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"298\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/04\/Image-1-300x298.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/04\/Image-1-300x298.jpg 300w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/04\/Image-1-1024x1016.jpg 1024w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/04\/Image-1-150x150.jpg 150w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/04\/Image-1-768x762.jpg 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/04\/Image-1-1536x1525.jpg 1536w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/04\/Image-1-2048x2033.jpg 2048w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/04\/Image-1-12x12.jpg 12w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/04\/Image-1-1088x1080.jpg 1088w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"Morocco\" class=\"fi fi-ma\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Mouad Khaznaoui, Ing.<\/p>\n\n\n                                                            <p class=\"function\">Ing\u00e9nieur logiciel &#8211; Data scientist<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/mouadkhaznaoui\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Mouad Khaznaoui, Ing.\"><\/a>\n                                                                                                                <a target=\"_blank\" href=\"https:\/\/bwi.earth\/mouad-khaznaoui\/\" class=\"icon-team icon-url\" title=\"Url of  Mouad Khaznaoui, Ing.\"><span><\/span><\/a>\n                                                                    <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/aiten-300x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/aiten-300x300.jpeg 300w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/aiten-150x150.jpeg 150w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/aiten-768x768.jpeg 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/aiten.jpeg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"Spain\" class=\"fi fi-es\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Aiten Alava, M.Sc.<\/p>\n\n\n                                                            <p class=\"function\">Data scientist<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/aitenalava\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Aiten Alava, M.Sc.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"271\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/issam-e1773332419731-300x271.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/issam-e1773332419731-300x271.jpeg 300w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/issam-e1773332419731.jpeg 317w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Issam El Kadiri, Ing.<\/p>\n\n\n                                                            <p class=\"function\">Data scientist<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/issam-979\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Issam El Kadiri, Ing.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/kartik-300x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/kartik-300x300.jpeg 300w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/kartik-150x150.jpeg 150w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/kartik-768x768.jpeg 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/kartik.jpeg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"India\" class=\"fi fi-in\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Kartik Gera, M.Sc.<\/p>\n\n\n                                                            <p class=\"function\">Ing\u00e9nieur senior big data<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/kartik-gera\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Kartik Gera, M.Sc.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/jeremy-g-300x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/jeremy-g-300x300.jpeg 300w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/jeremy-g-150x150.jpeg 150w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/jeremy-g-768x768.jpeg 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/jeremy-g.jpeg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Jeremy Gak, Ing.<\/p>\n\n\n                                                            <p class=\"function\">Ing\u00e9nieur DevOps<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/jeremy-g-57abb95b\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Jeremy Gak, Ing.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/06\/1-1-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/06\/1-1-300x300.jpg 300w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/06\/1-1-1024x1024.jpg 1024w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/06\/1-1-150x150.jpg 150w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/06\/1-1-768x768.jpg 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/06\/1-1.jpg 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Cl\u00e9ment Xanxo, M.A.<\/p>\n\n\n                                                            <p class=\"function\">Responsable du d\u00e9veloppement commercial pour la France<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/cl%C3%A9ment-xanxo-5a61211a2\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Cl\u00e9ment Xanxo, M.A.\"><\/a>\n                                                                                                                <a target=\"_blank\" href=\"https:\/\/bwi.earth\/clement-xanxo\/\" class=\"icon-team icon-url\" title=\"Url of  Cl\u00e9ment Xanxo, M.A.\"><span><\/span><\/a>\n                                                                    <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"262\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/IMG_8189-1-1-262x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/IMG_8189-1-1-262x300.jpg 262w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/IMG_8189-1-1.jpg 634w\" sizes=\"auto, (max-width: 262px) 100vw, 262px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"Vietnam\" class=\"fi fi-vn\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Thuy Dung Vu, M.Sc.<\/p>\n\n\n                                                            <p class=\"function\">Responsable Marketing et Communication<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/thuydungvu8998\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Thuy Dung Vu, M.Sc.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/HD_Portrait-16-1-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/HD_Portrait-16-1-200x300.jpg 200w, https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/HD_Portrait-16-1-683x1024.jpg 683w, https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/HD_Portrait-16-1-768x1152.jpg 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/HD_Portrait-16-1-1024x1536.jpg 1024w, https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/HD_Portrait-16-1-1365x2048.jpg 1365w, https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/HD_Portrait-16-1-720x1080.jpg 720w, https:\/\/bwi.earth\/wp-content\/uploads\/2025\/05\/HD_Portrait-16-1-scaled.jpg 1707w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Anne-Sophie Devallet, M.Sc. <\/p>\n\n\n                                                            <p class=\"function\">Charg\u00e9e de missions<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/anne-sophie-devallet-83131618a\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Anne-Sophie Devallet, M.Sc. \"><\/a>\n                                                                                                                <a target=\"_blank\" href=\"https:\/\/bwi.earth\/introducing-anne-sophie-devallet\/\" class=\"icon-team icon-url\" title=\"Url of  Anne-Sophie Devallet, M.Sc. \"><span><\/span><\/a>\n                                                                    <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Sept_2025-126-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Sept_2025-126-200x300.jpg 200w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Sept_2025-126-683x1024.jpg 683w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Sept_2025-126-768x1152.jpg 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Sept_2025-126-1024x1536.jpg 1024w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Sept_2025-126-720x1080.jpg 720w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/RS_BWI_Sept_2025-126.jpg 1365w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"Morocco\" class=\"fi fi-ma\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Chaymae Adlane, Ing.<\/p>\n\n\n                                                            <p class=\"function\">Ing\u00e9nieur logiciel<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/chaymae-a-7182582a0\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Chaymae Adlane, Ing.\"><\/a>\n                                                                                                                <a target=\"_blank\" href=\"https:\/\/bwi.earth\/introducing-chaymae-adlane-software-engineer\/\" class=\"icon-team icon-url\" title=\"Url of  Chaymae Adlane, Ing.\"><span><\/span><\/a>\n                                                                    <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"278\" height=\"278\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/1725497637295.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/1725497637295.jpeg 278w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/02\/1725497637295-150x150.jpeg 150w\" sizes=\"auto, (max-width: 278px) 100vw, 278px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Nassim Faraoun, M.Sc.<\/p>\n\n\n                                                            <p class=\"function\">Analyste commercial junior<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/nassim-faraoun-2a1853308\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Nassim Faraoun, M.Sc.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"262\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/Image-18-300x262.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/Image-18-300x262.jpeg 300w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/Image-18-768x670.jpeg 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/Image-18.jpeg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Hugo Tricou, M.Sc.<\/p>\n\n\n                                                            <p class=\"function\">Analyste commercial junior<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/hugo-tricou-b39a01233\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Hugo Tricou, M.Sc.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"236\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/06\/photo-236x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/06\/photo-236x300.jpeg 236w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/06\/photo.jpeg 481w\" sizes=\"auto, (max-width: 236px) 100vw, 236px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"France\" class=\"fi fi-fr\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Gavriel Langer, Ing.<\/p>\n\n\n                                                            <p class=\"function\">Ing\u00e9nieur DevOps junior<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/gavriel-langer\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Gavriel Langer, Ing.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                                            <div class=\"slide swiper-slide collaborator\">\n                           \n                                <div class=\"picture\">\n                            \n                                <div class=\"shape-external shape-blue\">\n                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/06\/fadel.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/06\/fadel.png 300w, https:\/\/bwi.earth\/wp-content\/uploads\/2026\/06\/fadel-150x150.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                                                                    <\/div>\n                            <\/div>\n\n                             <!-- BEGIN Flags -->\n                                                                                                            <div class=\"flags-wrapper\">\n                                                                                    <span title=\"Senegal\" class=\"fi fi-sn\"><\/span>\n                                                                                <\/div>\n                                                                                            <!-- END Flags -->                    \n\n\n                            <p class=\"name\">Fadel Mohamed Thiam, M.Sc.<\/p>\n\n\n                                                            <p class=\"function\">Assistant financier<\/p>\n                                                         \n                                <div class=\"linkedin\">\n                                                                            <a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/in\/mohamed-fadel-thiam-791946316\/\" class=\"icon-team icon-linkedin\" title=\"Linkedin of  Fadel Mohamed Thiam, M.Sc.\"><\/a>\n                                                                                                        <\/div>\n                           \n                        <\/div>\n                    \n                                            <div class=\"infos-desktop slide swiper-slide tk-trade-gothic-next-condensed\">\n                            <p><b>+ 10 postes \u00e0 temps plein ouverts <\/b>\u00e0 Toulouse et \u00e0 Paris<\/p>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n\n                            <div class=\"infos infos-mobile tk-trade-gothic-next-condensed\">\n                    <p><b>+ 10 postes \u00e0 temps plein ouverts <\/b>\u00e0 Toulouse et \u00e0 Paris<\/p>\n                <\/div>\n                    <\/div>\n    <\/section>\n\n\n\n<section class=\"gut-rebond bg-color-bleu-elec baseline\">\n    <div class=\"wrap\">\n        <div class=\"left\">\n                            <h2 class=\"block-title title-h2\">Vous souhaitez<b> nous rejoindre <\/b>?<\/h2>\n            \n                            <p class=\"baseline tk-trade-gothic-next-condensed\">Postuler \u00e0 BWI<\/p>\n                    <\/div>\n\n        <div class=\"right\">\n            <p class=\"content\">\n                Visitez notre page Carri\u00e8res et envoyez-nous un message avec l&rsquo;URL de votre profil LinkedIn.            <\/p>\n\n                            <a href=\"https:\/\/bwi.earth\/join-the-bwi-team\/\" class=\"cta btn primary green\">Postes ouverts chez BWI<\/a>\n                    <\/div>\n    <\/div>\n<\/section>\n\n    <section class=\"partners\">\n        <div class=\"wrap\">\n                            <h2 class=\"block-title title-h2\"><p>Notre <b>actionnaire de r\u00e9f\u00e9rence<\/b>, Hemeria, d\u00e9tient une participation minoritaire (&lt;10%) dans BWI :<br><\/p><\/h2>\n            \n            <div class=\"swiper\">\n                <div class=\"swiper-wrapper count-1\">\n                                            <div class=\"swiper-slide\">\n                                                            <a href=\"https:\/\/www.hemeria-group.com\/\" target=\"_blank\" class=\"logo\">\n                            \n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"250\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/logo_hemeria-300x250.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/logo_hemeria-300x250.png 300w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/logo_hemeria.png 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                            \n                                                            <\/a>\n                                                    <\/div>\n                                    <\/div>\n            <\/div>\n\n            <div class=\"partners__navigation\">\n                <button class=\"partners__navigation--prev\"><span class=\"icon-chevron-right\"><\/span><span class=\"label\">Previous<\/span><\/button>\n\n                <div class=\"partners__pagination\"><\/div>\n                \n                <button class=\"partners__navigation--next\"><span class=\"label\">Next<\/span> <span class=\"icon-chevron-right\"><\/span><\/button>\n            <\/div>\n        <\/div>\n    <\/section>\n\n\n    <section class=\"partners\">\n        <div class=\"wrap\">\n                            <h2 class=\"block-title title-h2\"><p>BWI est fi\u00e8re d&rsquo;\u00eatre r\u00e9sidente d&rsquo;un<b> acc\u00e9l\u00e9rateur de startups <\/b>nomm\u00e9 DISTRICT :<br><\/p><\/h2>\n            \n            <div class=\"swiper\">\n                <div class=\"swiper-wrapper count-1\">\n                                            <div class=\"swiper-slide\">\n                                                            <a href=\"https:\/\/www.aerospace-valley.com\/en\/support-and-development-your-innovative-activity-district\" target=\"_blank\" class=\"logo\">\n                            \n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"211\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/05\/logo-District-by-aero-1-orange-300x211.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/05\/logo-District-by-aero-1-orange-300x211.png 300w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/05\/logo-District-by-aero-1-orange.png 377w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                            \n                                                            <\/a>\n                                                    <\/div>\n                                    <\/div>\n            <\/div>\n\n            <div class=\"partners__navigation\">\n                <button class=\"partners__navigation--prev\"><span class=\"icon-chevron-right\"><\/span><span class=\"label\">Previous<\/span><\/button>\n\n                <div class=\"partners__pagination\"><\/div>\n                \n                <button class=\"partners__navigation--next\"><span class=\"label\">Next<\/span> <span class=\"icon-chevron-right\"><\/span><\/button>\n            <\/div>\n        <\/div>\n    <\/section>\n\n\n    <section class=\"partners\">\n        <div class=\"wrap\">\n                            <h2 class=\"block-title title-h2\"><p>BWI est l\u2019heureuse incub\u00e9e  d&rsquo;<b>ESA BIC Sud France<\/b> :<br><\/p><\/h2>\n            \n            <div class=\"swiper\">\n                <div class=\"swiper-wrapper count-1\">\n                                            <div class=\"swiper-slide\">\n                                                            <a href=\"https:\/\/www.esabicsud.fr\/incub%C3%A9s\" target=\"_blank\" class=\"logo\">\n                            \n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"137\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/07\/ESA_BIC_Sud-France-Bleu-e1720009760940-300x137.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/07\/ESA_BIC_Sud-France-Bleu-e1720009760940-300x137.png 300w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/07\/ESA_BIC_Sud-France-Bleu-e1720009760940-1024x466.png 1024w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/07\/ESA_BIC_Sud-France-Bleu-e1720009760940-768x350.png 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/07\/ESA_BIC_Sud-France-Bleu-e1720009760940-1536x699.png 1536w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/07\/ESA_BIC_Sud-France-Bleu-e1720009760940-1920x874.png 1920w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/07\/ESA_BIC_Sud-France-Bleu-e1720009760940.png 1971w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                            \n                                                            <\/a>\n                                                    <\/div>\n                                    <\/div>\n            <\/div>\n\n            <div class=\"partners__navigation\">\n                <button class=\"partners__navigation--prev\"><span class=\"icon-chevron-right\"><\/span><span class=\"label\">Previous<\/span><\/button>\n\n                <div class=\"partners__pagination\"><\/div>\n                \n                <button class=\"partners__navigation--next\"><span class=\"label\">Next<\/span> <span class=\"icon-chevron-right\"><\/span><\/button>\n            <\/div>\n        <\/div>\n    <\/section>\n\n\n    <section class=\"partners\">\n        <div class=\"wrap\">\n                            <h2 class=\"block-title title-h2\"><p>BWI est un membre de l&rsquo;<b>initiative SCALE<\/b> d&rsquo;Aerospace Valley :<br><\/p><\/h2>\n            \n            <div class=\"swiper\">\n                <div class=\"swiper-wrapper count-1\">\n                                            <div class=\"swiper-slide\">\n                                                            <a href=\"https:\/\/space-climate-league.com\" target=\"_blank\" class=\"logo\">\n                            \n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"173\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/10\/Untitled-design-2-e1729455161666-300x173.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/10\/Untitled-design-2-e1729455161666-300x173.png 300w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/10\/Untitled-design-2-e1729455161666-1024x589.png 1024w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/10\/Untitled-design-2-e1729455161666-768x442.png 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/10\/Untitled-design-2-e1729455161666.png 1178w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                            \n                                                            <\/a>\n                                                    <\/div>\n                                    <\/div>\n            <\/div>\n\n            <div class=\"partners__navigation\">\n                <button class=\"partners__navigation--prev\"><span class=\"icon-chevron-right\"><\/span><span class=\"label\">Previous<\/span><\/button>\n\n                <div class=\"partners__pagination\"><\/div>\n                \n                <button class=\"partners__navigation--next\"><span class=\"label\">Next<\/span> <span class=\"icon-chevron-right\"><\/span><\/button>\n            <\/div>\n        <\/div>\n    <\/section>\n\n\n    <section class=\"partners\">\n        <div class=\"wrap\">\n                            <h2 class=\"block-title title-h2\"><p>BWI est soutenue par <b>Airbus D\u00e9veloppement<\/b><\/p><\/h2>\n            \n            <div class=\"swiper\">\n                <div class=\"swiper-wrapper count-1\">\n                                            <div class=\"swiper-slide\">\n                                                            <a href=\"https:\/\/www.linkedin.com\/company\/airbus-developpement\/\" target=\"_blank\" class=\"logo\">\n                            \n                            <img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2026\/03\/airbus-dev-scaled.png\" class=\"attachment-medium size-medium\" alt=\"\" \/>                            \n                                                            <\/a>\n                                                    <\/div>\n                                    <\/div>\n            <\/div>\n\n            <div class=\"partners__navigation\">\n                <button class=\"partners__navigation--prev\"><span class=\"icon-chevron-right\"><\/span><span class=\"label\">Previous<\/span><\/button>\n\n                <div class=\"partners__pagination\"><\/div>\n                \n                <button class=\"partners__navigation--next\"><span class=\"label\">Next<\/span> <span class=\"icon-chevron-right\"><\/span><\/button>\n            <\/div>\n        <\/div>\n    <\/section>\n\n\n    <section class=\"partners\">\n        <div class=\"wrap\">\n                            <h2 class=\"block-title title-h2\"><p><b>Partenaires techniques<\/b> de BWI<br><\/p><\/h2>\n            \n            <div class=\"swiper\">\n                <div class=\"swiper-wrapper count-11\">\n                                            <div class=\"swiper-slide\">\n                                                            <a href=\"https:\/\/www.aerospace-valley.com\/\" target=\"_blank\" class=\"logo\">\n                            \n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/aerospace_valley-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/aerospace_valley-300x300.png 300w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/aerospace_valley-150x150.png 150w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/aerospace_valley-768x768.png 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/aerospace_valley.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                            \n                                                            <\/a>\n                                                    <\/div>\n                                            <div class=\"swiper-slide\">\n                                                            <a href=\"https:\/\/aqua-valley.com\/\" target=\"_blank\" class=\"logo\">\n                            \n                            <img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/aquavalley.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/aquavalley.png 250w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/aquavalley-150x150.png 150w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/>                            \n                                                            <\/a>\n                                                    <\/div>\n                                            <div class=\"swiper-slide\">\n                                                            <a href=\"https:\/\/francedigitale.org\" target=\"_blank\" class=\"logo\">\n                            \n                            <img loading=\"lazy\" decoding=\"async\" width=\"278\" height=\"278\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/07\/https___cdn.evbuc_.com_images_448746609_131845335838_1_original.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/07\/https___cdn.evbuc_.com_images_448746609_131845335838_1_original.png 278w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/07\/https___cdn.evbuc_.com_images_448746609_131845335838_1_original-150x150.png 150w\" sizes=\"auto, (max-width: 278px) 100vw, 278px\" \/>                            \n                                                            <\/a>\n                                                    <\/div>\n                                            <div class=\"swiper-slide\">\n                                                            <a href=\"https:\/\/www.inrae.fr\" target=\"_blank\" class=\"logo\">\n                            \n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"79\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/06\/Logo-INRAE_Transparent.svg-1-300x79.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/06\/Logo-INRAE_Transparent.svg-1-300x79.png 300w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/06\/Logo-INRAE_Transparent.svg-1-1024x270.png 1024w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/06\/Logo-INRAE_Transparent.svg-1-768x203.png 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/06\/Logo-INRAE_Transparent.svg-1.png 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                            \n                                                            <\/a>\n                                                    <\/div>\n                                            <div class=\"swiper-slide\">\n                                                            <a href=\"https:\/\/programmes.insu.cnrs.fr\/lefe\/\" target=\"_blank\" class=\"logo\">\n                            \n                            <img loading=\"lazy\" decoding=\"async\" width=\"210\" height=\"300\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/06\/lefe-1-210x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/06\/lefe-1-210x300.png 210w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/06\/lefe-1-715x1024.png 715w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/06\/lefe-1-768x1100.png 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/06\/lefe-1-1073x1536.png 1073w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/06\/lefe-1-1430x2048.png 1430w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/06\/lefe-1-754x1080.png 754w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/>                            \n                                                            <\/a>\n                                                    <\/div>\n                                            <div class=\"swiper-slide\">\n                                                            <a href=\"https:\/\/www.lis-lab.fr\" target=\"_blank\" class=\"logo\">\n                            \n                            <img loading=\"lazy\" decoding=\"async\" width=\"293\" height=\"228\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/logo-lis.png\" class=\"attachment-medium size-medium\" alt=\"\" \/>                            \n                                                            <\/a>\n                                                    <\/div>\n                                            <div class=\"swiper-slide\">\n                                                            <a href=\"https:\/\/www.ign.fr\" target=\"_blank\" class=\"logo\">\n                            \n                            <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"659\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/04\/IGN_logo_2012.svg\" class=\"attachment-medium size-medium\" alt=\"\" \/>                            \n                                                            <\/a>\n                                                    <\/div>\n                                            <div class=\"swiper-slide\">\n                                                            <a href=\"https:\/\/meoss.net\/\" target=\"_blank\" class=\"logo\">\n                            \n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"62\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/03\/MEOSS-300x62.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/03\/MEOSS-300x62.png 300w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/03\/MEOSS-1024x211.png 1024w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/03\/MEOSS-768x159.png 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/03\/MEOSS-1536x317.png 1536w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/03\/MEOSS-2048x423.png 2048w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/03\/MEOSS-18x4.png 18w, https:\/\/bwi.earth\/wp-content\/uploads\/2024\/03\/MEOSS-1920x396.png 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                            \n                                                            <\/a>\n                                                    <\/div>\n                                            <div class=\"swiper-slide\">\n                                                            <a href=\"https:\/\/inrm.co.in\" target=\"_blank\" class=\"logo\">\n                            \n                            <img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/05\/1583405282612-removebg-preview.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/05\/1583405282612-removebg-preview.png 200w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/05\/1583405282612-removebg-preview-150x150.png 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>                            \n                                                            <\/a>\n                                                    <\/div>\n                                            <div class=\"swiper-slide\">\n                                                            <a href=\"http:\/\/www.sfpt.fr\" target=\"_blank\" class=\"logo\">\n                            \n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"257\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/05\/SFPT-logo-300x257.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/05\/SFPT-logo-300x257.png 300w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/05\/SFPT-logo-768x659.png 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/05\/SFPT-logo.png 979w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                            \n                                                            <\/a>\n                                                    <\/div>\n                                            <div class=\"swiper-slide\">\n                                                            <a href=\"https:\/\/www.scaleway.com\/en\/\" target=\"_blank\" class=\"logo\">\n                            \n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"73\" src=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/scaleway-300x73.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/scaleway-300x73.png 300w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/scaleway-1024x248.png 1024w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/scaleway-768x186.png 768w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/scaleway-1536x372.png 1536w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/scaleway-2048x496.png 2048w, https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/scaleway-1920x465.png 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                            \n                                                            <\/a>\n                                                    <\/div>\n                                    <\/div>\n            <\/div>\n\n            <div class=\"partners__navigation\">\n                <button class=\"partners__navigation--prev\"><span class=\"icon-chevron-right\"><\/span><span class=\"label\">Previous<\/span><\/button>\n\n                <div class=\"partners__pagination\"><\/div>\n                \n                <button class=\"partners__navigation--next\"><span class=\"label\">Next<\/span> <span class=\"icon-chevron-right\"><\/span><\/button>\n            <\/div>\n        <\/div>\n    <\/section>\n\n\n\n<section class=\"gut-rebond bg-color-bleu-elec baseline\">\n    <div class=\"wrap\">\n        <div class=\"left\">\n                            <h2 class=\"block-title title-h2\">Nous serions ravis de vous rencontrer !\u00a0<\/h2>\n            \n                            <p class=\"baseline tk-trade-gothic-next-condensed\">Contactez-nous<\/p>\n                    <\/div>\n\n        <div class=\"right\">\n            <p class=\"content\">\n                Que vous soyez un talent \u00e0 la recherche d&rsquo;un nouveau d\u00e9fi (envoyez-nous votre CV), un journaliste couvrant des solutions de r\u00e9silience climatique (nous racontons une histoire d&rsquo;espoir et de passion), un fonds de capital-risque d\u00e9sireux d&rsquo;investir dans un avenir durable (les crises pr\u00e9sentent souvent une opportunit\u00e9), un client potentiel (cherchant \u00e0 se prot\u00e9ger contre le changement climatique en num\u00e9risant ses bassins d&rsquo;int\u00e9r\u00eat), ou un futur partenaire, contactez-nous !            <\/p>\n\n                            <a href=\"https:\/\/bwi.earth\/contact\/\" class=\"cta btn primary green\">Contacter BWI<\/a>\n                    <\/div>\n    <\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":6193,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-29","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A propos<\/title>\n<meta name=\"description\" content=\"BWI, acronyme de Blue Water Intelligence, est une soci\u00e9t\u00e9 sp\u00e9cialis\u00e9e dans l\u2019hydrologie, cr\u00e9\u00e9e en juin 2022 \u00e0 Toulouse, en France.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bwi.earth\/fr\/a-propos\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A propos\" \/>\n<meta property=\"og:description\" content=\"BWI, acronyme de Blue Water Intelligence, est une soci\u00e9t\u00e9 sp\u00e9cialis\u00e9e dans l\u2019hydrologie, cr\u00e9\u00e9e en juin 2022 \u00e0 Toulouse, en France.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bwi.earth\/fr\/a-propos\/\" \/>\n<meta property=\"og:site_name\" content=\"Blue Water Intelligence (BWI)\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-09T10:32:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/04\/Team_BWI_03_04_2024-8-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bwi.earth\/fr\/a-propos\/\",\"url\":\"https:\/\/bwi.earth\/fr\/a-propos\/\",\"name\":\"A propos\",\"isPartOf\":{\"@id\":\"https:\/\/bwi.earth\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bwi.earth\/fr\/a-propos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bwi.earth\/fr\/a-propos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/04\/Team_BWI_03_04_2024-8-scaled.jpg\",\"datePublished\":\"2022-07-26T09:48:06+00:00\",\"dateModified\":\"2026-07-09T10:32:53+00:00\",\"description\":\"BWI, acronyme de Blue Water Intelligence, est une soci\u00e9t\u00e9 sp\u00e9cialis\u00e9e dans l\u2019hydrologie, cr\u00e9\u00e9e en juin 2022 \u00e0 Toulouse, en France.\",\"breadcrumb\":{\"@id\":\"https:\/\/bwi.earth\/fr\/a-propos\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bwi.earth\/fr\/a-propos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/bwi.earth\/fr\/a-propos\/#primaryimage\",\"url\":\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/04\/Team_BWI_03_04_2024-8-scaled.jpg\",\"contentUrl\":\"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/04\/Team_BWI_03_04_2024-8-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bwi.earth\/fr\/a-propos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/bwi.earth\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A propos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bwi.earth\/fr\/#website\",\"url\":\"https:\/\/bwi.earth\/fr\/\",\"name\":\"Blue Water Intelligence (BWI)\",\"description\":\"The River Basin Digitization Company\",\"publisher\":{\"@id\":\"https:\/\/bwi.earth\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bwi.earth\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bwi.earth\/fr\/#organization\",\"name\":\"Blue Water Intelligence (BWI)\",\"url\":\"https:\/\/bwi.earth\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/bwi.earth\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/cropped-logo_couleur_bwi.png\",\"contentUrl\":\"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/cropped-logo_couleur_bwi.png\",\"width\":4190,\"height\":1970,\"caption\":\"Blue Water Intelligence (BWI)\"},\"image\":{\"@id\":\"https:\/\/bwi.earth\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A propos","description":"BWI, acronyme de Blue Water Intelligence, est une soci\u00e9t\u00e9 sp\u00e9cialis\u00e9e dans l\u2019hydrologie, cr\u00e9\u00e9e en juin 2022 \u00e0 Toulouse, en France.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bwi.earth\/fr\/a-propos\/","og_locale":"fr_FR","og_type":"article","og_title":"A propos","og_description":"BWI, acronyme de Blue Water Intelligence, est une soci\u00e9t\u00e9 sp\u00e9cialis\u00e9e dans l\u2019hydrologie, cr\u00e9\u00e9e en juin 2022 \u00e0 Toulouse, en France.","og_url":"https:\/\/bwi.earth\/fr\/a-propos\/","og_site_name":"Blue Water Intelligence (BWI)","article_modified_time":"2026-07-09T10:32:53+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/04\/Team_BWI_03_04_2024-8-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bwi.earth\/fr\/a-propos\/","url":"https:\/\/bwi.earth\/fr\/a-propos\/","name":"A propos","isPartOf":{"@id":"https:\/\/bwi.earth\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bwi.earth\/fr\/a-propos\/#primaryimage"},"image":{"@id":"https:\/\/bwi.earth\/fr\/a-propos\/#primaryimage"},"thumbnailUrl":"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/04\/Team_BWI_03_04_2024-8-scaled.jpg","datePublished":"2022-07-26T09:48:06+00:00","dateModified":"2026-07-09T10:32:53+00:00","description":"BWI, acronyme de Blue Water Intelligence, est une soci\u00e9t\u00e9 sp\u00e9cialis\u00e9e dans l\u2019hydrologie, cr\u00e9\u00e9e en juin 2022 \u00e0 Toulouse, en France.","breadcrumb":{"@id":"https:\/\/bwi.earth\/fr\/a-propos\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bwi.earth\/fr\/a-propos\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bwi.earth\/fr\/a-propos\/#primaryimage","url":"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/04\/Team_BWI_03_04_2024-8-scaled.jpg","contentUrl":"https:\/\/bwi.earth\/wp-content\/uploads\/2024\/04\/Team_BWI_03_04_2024-8-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/bwi.earth\/fr\/a-propos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bwi.earth\/fr\/"},{"@type":"ListItem","position":2,"name":"A propos"}]},{"@type":"WebSite","@id":"https:\/\/bwi.earth\/fr\/#website","url":"https:\/\/bwi.earth\/fr\/","name":"Blue Water Intelligence (BWI)","description":"The River Basin Digitization Company","publisher":{"@id":"https:\/\/bwi.earth\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bwi.earth\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/bwi.earth\/fr\/#organization","name":"Blue Water Intelligence (BWI)","url":"https:\/\/bwi.earth\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bwi.earth\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/cropped-logo_couleur_bwi.png","contentUrl":"https:\/\/bwi.earth\/wp-content\/uploads\/2023\/03\/cropped-logo_couleur_bwi.png","width":4190,"height":1970,"caption":"Blue Water Intelligence (BWI)"},"image":{"@id":"https:\/\/bwi.earth\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/bwi.earth\/fr\/wp-json\/wp\/v2\/pages\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bwi.earth\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bwi.earth\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bwi.earth\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/bwi.earth\/fr\/wp-json\/wp\/v2\/comments?post=29"}],"version-history":[{"count":693,"href":"https:\/\/bwi.earth\/fr\/wp-json\/wp\/v2\/pages\/29\/revisions"}],"predecessor-version":[{"id":25105,"href":"https:\/\/bwi.earth\/fr\/wp-json\/wp\/v2\/pages\/29\/revisions\/25105"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bwi.earth\/fr\/wp-json\/wp\/v2\/media\/6193"}],"wp:attachment":[{"href":"https:\/\/bwi.earth\/fr\/wp-json\/wp\/v2\/media?parent=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}